{"id":53,"count":1,"description":"\u041d\u0430\u0431\u043e\u0440\u0438","link":"https:\/\/malvacosmopt.com\/ru\/product-category\/%d0%bd%d0%b0%d0%b1%d0%be%d1%80%d0%b8\/","name":"\u041d\u0430\u0431\u043e\u0440\u0438","slug":"%d0%bd%d0%b0%d0%b1%d0%be%d1%80%d0%b8","taxonomy":"product_cat","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/malvacosmopt.com\/ru\/wp-json\/wp\/v2\/product_cat\/53"}],"collection":[{"href":"https:\/\/malvacosmopt.com\/ru\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/malvacosmopt.com\/ru\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/malvacosmopt.com\/ru\/wp-json\/wp\/v2\/product?product_cat=53"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}